{"id":11902,"date":"2024-12-23T02:41:06","date_gmt":"2024-12-23T07:41:06","guid":{"rendered":"https:\/\/lions.financial\/?p=11902"},"modified":"2025-01-06T07:50:27","modified_gmt":"2025-01-06T12:50:27","slug":"top-5-things-investors-must-know-to-succeed-in-nyc-commercial-real-estate","status":"publish","type":"post","link":"https:\/\/lions.financial\/es\/top-5-things-investors-must-know-to-succeed-in-nyc-commercial-real-estate\/","title":{"rendered":"Las 5 cosas que los inversores deben saber para tener \u00e9xito en el sector inmobiliario comercial de Nueva York"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El mercado inmobiliario comercial de la ciudad de Nueva York es un terreno de juego en el que incluso los inversores m\u00e1s experimentados encuentran un reto. Como centro mundial de los negocios, la cultura y la innovaci\u00f3n, Nueva York ofrece oportunidades inigualables, pero esas oportunidades van acompa\u00f1adas de complejidades que exigen experiencia y previsi\u00f3n estrat\u00e9gica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En Lions Financial llevamos a\u00f1os guiando a los inversores por las complejidades del mercado neoyorquino. En esta gu\u00eda, vamos m\u00e1s all\u00e1 de lo b\u00e1sico, ofreciendo ideas pr\u00e1cticas adaptadas espec\u00edficamente al paisaje \u00fanico de la ciudad de Nueva York. Estas son las estrategias y consideraciones matizadas que necesita para tener \u00e9xito.<\/span><\/p>\n<h3><\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-12015\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-54.png\" alt=\"The Hyper-Local Market: Neighborhoods Matter More Than Ever\" width=\"1229\" height=\"158\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-54.png 1229w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-54-300x39.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-54-1024x132.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-54-768x99.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-54-18x2.png 18w\" sizes=\"(max-width: 1229px) 100vw, 1229px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">En Nueva York, la diferencia entre una inversi\u00f3n pr\u00f3spera y otra estancada se reduce a menudo a la geograf\u00eda, a veces a una sola manzana. Los inversores no pueden confiar en las tendencias de toda la ciudad, sino que deben profundizar en los datos hiperlocales.<\/span><\/p>\n<p><b>Lo que hay que tener en cuenta<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Mercados emergentes frente a mercados consolidados<\/b><span style=\"font-weight: 400;\">: Aunque zonas como Midtown y el distrito financiero son fiables, barrios emergentes como Gowanus, en Brooklyn, o el sur del Bronx ofrecen importantes ventajas a quienes est\u00e9n dispuestos a invertir pronto.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Proximidad del tr\u00e1nsito<\/b><span style=\"font-weight: 400;\">: Los inmuebles cercanos a l\u00edneas de metro en expansi\u00f3n o centros de tr\u00e1nsito (por ejemplo, la remodelaci\u00f3n de Penn Station) registran una mayor revalorizaci\u00f3n y demanda de inquilinos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Cambios en la zonificaci\u00f3n<\/b><span style=\"font-weight: 400;\">: Est\u00e9 atento a los barrios que se recalifican, como los del Soho y Gowanus. Las recalificaciones suelen desencadenar una oleada de nuevos desarrollos y un aumento del valor de la propiedad.<\/span><\/li>\n<\/ul>\n<p><b>Consejo profesional<\/b><span style=\"font-weight: 400;\">: Analice los patrones de tr\u00e1fico peatonal de los espacios comerciales y la composici\u00f3n de los inquilinos de las propiedades vecinas. Una alta concentraci\u00f3n de startups tecnol\u00f3gicas o empresas creativas puede indicar un fuerte crecimiento futuro de las inversiones en oficinas.<\/span><\/p>\n<p><b>C\u00f3mo ayuda Lions Financial<\/b><span style=\"font-weight: 400;\">: Proporcionamos informaci\u00f3n detallada sobre el mercado, analizando las tendencias a nivel de barrio para garantizar que su inversi\u00f3n se ajusta a la din\u00e1mica hiperlocal.<\/span><\/p>\n<h3><b><img decoding=\"async\" class=\"aligncenter size-full wp-image-12016\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-55.png\" alt=\"Financing in NYC: The Art of Creative Capital\" width=\"1229\" height=\"158\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-55.png 1229w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-55-300x39.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-55-1024x132.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-55-768x99.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-55-18x2.png 18w\" sizes=\"(max-width: 1229px) 100vw, 1229px\" \/><\/b><\/h3>\n<p><span style=\"font-weight: 400;\">El elevado valor de los inmuebles en Nueva York hace que la financiaci\u00f3n convencional a menudo no sea suficiente para cerrar operaciones, especialmente en situaciones de licitaci\u00f3n competitiva. Los inversores deben ser creativos a la hora de estructurar el capital.<\/span><\/p>\n<p><b>Lo que hay que tener en cuenta<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Capital apilado<\/b><span style=\"font-weight: 400;\">: Utilizar una combinaci\u00f3n de pr\u00e9stamos tradicionales, financiaci\u00f3n mezzanine y capital propio para reducir la dependencia de una sola fuente.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Pr\u00e9stamos puente<\/b><span style=\"font-weight: 400;\">: Estos pr\u00e9stamos a corto plazo son cruciales para los inversores que desean asegurarse propiedades r\u00e1pidamente mientras consiguen financiaci\u00f3n a largo plazo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Reducciones e incentivos fiscales<\/b><span style=\"font-weight: 400;\">: Programas como el 421a para nuevas construcciones residenciales o el ICAP para inmuebles comerciales pueden reducir significativamente los costes. Es fundamental saber c\u00f3mo aprovechar estos incentivos.<\/span><\/li>\n<\/ul>\n<p><b>Consejo profesional<\/b><span style=\"font-weight: 400;\">: En Nueva York, los prestamistas privados y las fuentes de financiaci\u00f3n alternativas a menudo tienen plazos de aprobaci\u00f3n m\u00e1s r\u00e1pidos que los bancos, lo que le da una ventaja en los mercados competitivos.<\/span><\/p>\n<p><b>C\u00f3mo ayuda Lions Financial<\/b><span style=\"font-weight: 400;\">: Ponemos en contacto a los inversores con una variada red de proveedores de capital, elaborando paquetes de financiaci\u00f3n dise\u00f1ados espec\u00edficamente para los matices de las transacciones en Nueva York.<\/span><\/p>\n<h3><img decoding=\"async\" class=\"aligncenter size-full wp-image-12019\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-58.png\" alt=\"\" width=\"1229\" height=\"158\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-58.png 1229w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-58-300x39.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-58-1024x132.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-58-768x99.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-58-18x2.png 18w\" sizes=\"(max-width: 1229px) 100vw, 1229px\" \/><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La demanda de inquilinos es el alma del sector inmobiliario comercial. Sin embargo, en Nueva York var\u00eda mucho seg\u00fan el sector y la ubicaci\u00f3n, lo que obliga a los inversores a adaptar sus opciones inmobiliarias a la realidad del mercado.<\/span><\/p>\n<p><b>Lo que hay que tener en cuenta<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Evoluci\u00f3n del comercio minorista<\/b><span style=\"font-weight: 400;\">: Los escaparates de primera en el Soho o el Meatpacking District siguen siendo codiciados, pero la pandemia ha reconfigurado el panorama del comercio minorista. Los inmuebles de uso mixto con log\u00edstica de comercio electr\u00f3nico integrada son cada vez m\u00e1s atractivos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Transformaci\u00f3n del espacio de oficinas<\/b><span style=\"font-weight: 400;\">: Los dise\u00f1os flexibles, los espacios de trabajo conjunto y los servicios como las zonas de bienestar son ahora innegociables para atraer inquilinos. Busque oficinas de clase A en barrios orientados a las industrias tecnol\u00f3gicas y creativas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Tendencias multifamiliares<\/b><span style=\"font-weight: 400;\">: La demanda de apartamentos de lujo sigue siendo alta en Manhattan, pero barrios perif\u00e9ricos como Queens y Brooklyn atraen a inquilinos que buscan asequibilidad con servicios modernos.<\/span><\/li>\n<\/ul>\n<p><b>Consejo profesional<\/b><span style=\"font-weight: 400;\">: Las preferencias de los inquilinos tras el COVID se inclinan por los espacios que dan prioridad a la experiencia. Pensemos en terrazas en azoteas, servicios compartidos y elementos de sostenibilidad con certificaci\u00f3n LEED.<\/span><\/p>\n<p><b>C\u00f3mo ayuda Lions Financial<\/b><span style=\"font-weight: 400;\">: Analizamos las tendencias de la demanda de inquilinos en todos los sectores, ayud\u00e1ndole a elegir propiedades que atiendan a inquilinos de alta demanda, garantizando un flujo de caja estable y valor a largo plazo.<\/span><\/p>\n<h3><b><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12020\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-59.png\" alt=\"NYC\u2019s Regulatory Labyrinth: Know Before You Buy\" width=\"1229\" height=\"158\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-59.png 1229w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-59-300x39.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-59-1024x132.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-59-768x99.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-59-18x2.png 18w\" sizes=\"(max-width: 1229px) 100vw, 1229px\" \/><\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Navegar por el complejo entorno normativo de Nueva York suele ser el mayor reto para los inversores. Las leyes de zonificaci\u00f3n, los c\u00f3digos de construcci\u00f3n y los requisitos de cumplimiento pueden hacer o deshacer un trato.<\/span><\/p>\n<p><b>Lo que hay que tener en cuenta<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Cambios en la zonificaci\u00f3n<\/b><span style=\"font-weight: 400;\">: Los inmuebles comercializados como oportunidades de uso mixto o reurbanizaci\u00f3n pueden enfrentarse a importantes obst\u00e1culos de zonificaci\u00f3n. Verifique los casos de uso con los departamentos de urbanismo de la ciudad.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Designaciones hist\u00f3ricas<\/b><span style=\"font-weight: 400;\">: Los edificios de los distritos hist\u00f3ricos se enfrentan a normativas m\u00e1s estrictas en materia de reformas y reurbanizaci\u00f3n.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Derechos a\u00e9reos<\/b><span style=\"font-weight: 400;\">: En Nueva York, la posibilidad de comprar o vender derechos a\u00e9reos no utilizados (derechos de desarrollo) puede repercutir significativamente en el valor y el potencial de una propiedad.<\/span><\/li>\n<\/ul>\n<p><b>Consejo profesional<\/b><span style=\"font-weight: 400;\">: Incluya siempre a un abogado especializado en zonificaci\u00f3n y a un experto en cumplimiento de la normativa en su equipo de diligencia debida para evitar retrasos o costes inesperados.<\/span><\/p>\n<p><b>C\u00f3mo ayuda Lions Financial<\/b><span style=\"font-weight: 400;\">: Trabajamos con especialistas en zonificaci\u00f3n y profesionales jur\u00eddicos para garantizar que su propiedad se ajusta al uso previsto y mitiga los riesgos normativos.<\/span><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12021\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-60.png\" alt=\"Exit Strategies: Plan from Day One\" width=\"1229\" height=\"158\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-60.png 1229w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-60-300x39.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-60-1024x132.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-60-768x99.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-60-18x2.png 18w\" sizes=\"(max-width: 1229px) 100vw, 1229px\" \/><\/h3>\n<p><span style=\"font-weight: 400;\">Toda inversi\u00f3n de \u00e9xito comienza con una estrategia de salida clara. En un mercado tan cambiante como el de Nueva York, es fundamental saber c\u00f3mo y cu\u00e1ndo rentabilizar la inversi\u00f3n.<\/span><\/p>\n<p><b>Lo que hay que tener en cuenta<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Flipping vs. Holding<\/b><span style=\"font-weight: 400;\">: Los barrios de alta demanda pueden permitir cambios r\u00e1pidos, mientras que las zonas emergentes son m\u00e1s adecuadas para mantener a largo plazo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Optimizaci\u00f3n de las plusval\u00edas<\/b><span style=\"font-weight: 400;\">: Explore los intercambios 1031 para aplazar los impuestos sobre las ganancias reinvirtiendo en propiedades similares.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Market Timing<\/b><span style=\"font-weight: 400;\">: El mercado de Nueva York es c\u00edclico. Supervise indicadores econ\u00f3micos como los tipos de inter\u00e9s y las tendencias de vacantes para identificar los mejores momentos para vender.<\/span><\/li>\n<\/ul>\n<p><b>Consejo profesional<\/b><span style=\"font-weight: 400;\">: Siga las tendencias de la tasa de capitalizaci\u00f3n en el \u00e1rea de su propiedad para determinar cu\u00e1ndo vender para obtener el m\u00e1ximo retorno de la inversi\u00f3n.<\/span><\/p>\n<p><b>C\u00f3mo ayuda Lions Financial<\/b><span style=\"font-weight: 400;\">: Desde la adquisici\u00f3n hasta la enajenaci\u00f3n, guiamos a los inversores en todas las fases del proceso, garantizando que su estrategia de salida se ajuste a las condiciones del mercado y a sus objetivos financieros.<\/span><\/p>\n<h3><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12022\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-62.png\" alt=\"Why Investors Partner with Lions Financial\" width=\"1229\" height=\"158\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-62.png 1229w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-62-300x39.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-62-1024x132.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-62-768x99.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/Inside-title-design-project-62-18x2.png 18w\" sizes=\"(max-width: 1229px) 100vw, 1229px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">El mercado inmobiliario comercial de Nueva York no es para los d\u00e9biles de coraz\u00f3n, pero con los socios adecuados, se convierte en un patio de recreo para los inversores estrat\u00e9gicos. Lions Financial ofrece:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Profundo conocimiento del mercado<\/b><span style=\"font-weight: 400;\">: Perspectivas que van m\u00e1s all\u00e1 de las tendencias superficiales.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Soluciones de financiaci\u00f3n a medida<\/b><span style=\"font-weight: 400;\">: Acceso a estrategias de capital dise\u00f1adas para el mercado \u00fanico de Nueva York.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Apoyo integral<\/b><span style=\"font-weight: 400;\">: Desde la diligencia debida hasta la planificaci\u00f3n de la salida, estamos con usted en cada paso del camino.<\/span><\/li>\n<\/ul>\n<h3><b>\u00bfListo para triunfar en el sector inmobiliario de Nueva York?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Tanto si es un inversor experimentado como si est\u00e1 explorando su primera propiedad en Nueva York, el \u00e9xito comienza con la preparaci\u00f3n y el equipo adecuado. P\u00f3ngase en contacto con Lions Financial hoy mismo para programar una consulta y desbloquear todo el potencial del mercado inmobiliario comercial de Nueva York.<\/span><\/p>\n<p><b>Su pr\u00f3xima gran inversi\u00f3n le est\u00e1 esperando: hag\u00e1mosla realidad.<\/b><\/p>\n<p><a href=\"https:\/\/lions.financial\/es\/contact\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12014\" src=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2.png\" alt=\"Top 5 Things Investors Must Know to Succeed in NYC Commercial Real Estate\" width=\"957\" height=\"538\" srcset=\"https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2.png 1920w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2-300x169.png 300w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2-1024x576.png 1024w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2-768x432.png 768w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2-1536x864.png 1536w, https:\/\/lions.financial\/wp-content\/uploads\/2024\/12\/LS-Cover-2-18x10.png 18w\" sizes=\"(max-width: 957px) 100vw, 957px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>New York City\u2019s commercial real estate market is a high-stakes arena that even the most seasoned investors find challenging. As a global hub for business, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12074,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[90,361],"tags":[],"ppma_author":[386],"class_list":["post-11902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-planning","category-insights","author-research-team"],"acf":[],"authors":[{"term_id":386,"user_id":0,"is_guest":1,"slug":"research-team","display_name":"Research Team","avatar_url":{"url":"https:\/\/lions.financial\/wp-content\/uploads\/2018\/12\/cropped-LIons-Assurance-Financial-Logo-Favicon.png","url2x":"https:\/\/lions.financial\/wp-content\/uploads\/2018\/12\/cropped-LIons-Assurance-Financial-Logo-Favicon.png"},"author_category":"","user_url":"","last_name":"","first_name":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/posts\/11902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/comments?post=11902"}],"version-history":[{"count":4,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/posts\/11902\/revisions"}],"predecessor-version":[{"id":12025,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/posts\/11902\/revisions\/12025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/media\/12074"}],"wp:attachment":[{"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/media?parent=11902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/categories?post=11902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/tags?post=11902"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/lions.financial\/es\/wp-json\/wp\/v2\/ppma_author?post=11902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}